{"id":4847,"date":"2024-06-18T18:47:35","date_gmt":"2024-06-18T16:47:35","guid":{"rendered":"http:\/\/www.snepfsu-martinique.net\/?p=4847"},"modified":"2024-06-18T18:51:42","modified_gmt":"2024-06-18T16:51:42","slug":"video-snep-972-pour-les-4h-deps-pour-tous","status":"publish","type":"post","link":"https:\/\/www.snepfsu-martinique.net\/index.php\/2024\/06\/18\/video-snep-972-pour-les-4h-deps-pour-tous\/","title":{"rendered":"VIDEO SNEP 972 pour les 4H d&rsquo;EPS pour tous"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.snepfsu-martinique.net\/wp-content\/uploads\/2024\/06\/434109481_2641758689359754_2637620301668746855_n-1024x769.jpg\" alt=\"\" class=\"wp-image-4845\" width=\"374\" height=\"281\" srcset=\"https:\/\/www.snepfsu-martinique.net\/wp-content\/uploads\/2024\/06\/434109481_2641758689359754_2637620301668746855_n-1024x769.jpg 1024w, https:\/\/www.snepfsu-martinique.net\/wp-content\/uploads\/2024\/06\/434109481_2641758689359754_2637620301668746855_n-300x225.jpg 300w, https:\/\/www.snepfsu-martinique.net\/wp-content\/uploads\/2024\/06\/434109481_2641758689359754_2637620301668746855_n-768x577.jpg 768w, https:\/\/www.snepfsu-martinique.net\/wp-content\/uploads\/2024\/06\/434109481_2641758689359754_2637620301668746855_n.jpg 1280w\" sizes=\"(max-width: 374px) 100vw, 374px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-video\"><video controls src=\"http:\/\/www.snepfsu-martinique.net\/wp-content\/uploads\/2024\/06\/An9s-Y2HtjQNjHU8X1h2IvS3upz73A0LmwAgl7wF6Wtb3WOrAC_8HRUC7DZ1fgpIWXusMG7BFwH2FWkmnklmGnme.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.snepfsu-martinique.net\/index.php\/wp-json\/wp\/v2\/posts\/4847"}],"collection":[{"href":"https:\/\/www.snepfsu-martinique.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snepfsu-martinique.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snepfsu-martinique.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snepfsu-martinique.net\/index.php\/wp-json\/wp\/v2\/comments?post=4847"}],"version-history":[{"count":2,"href":"https:\/\/www.snepfsu-martinique.net\/index.php\/wp-json\/wp\/v2\/posts\/4847\/revisions"}],"predecessor-version":[{"id":4850,"href":"https:\/\/www.snepfsu-martinique.net\/index.php\/wp-json\/wp\/v2\/posts\/4847\/revisions\/4850"}],"wp:attachment":[{"href":"https:\/\/www.snepfsu-martinique.net\/index.php\/wp-json\/wp\/v2\/media?parent=4847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snepfsu-martinique.net\/index.php\/wp-json\/wp\/v2\/categories?post=4847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snepfsu-martinique.net\/index.php\/wp-json\/wp\/v2\/tags?post=4847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}